{"id":82,"count":3,"description":"<div style=\"text-align: left;padding: 0% 15% 5px 15%\">\r\n<h2 style=\"line-height: 100%\">Sacchi da boxe con sistema brevettato<\/h2>\r\nProduciamo<strong> sacchi da boxe<\/strong>, completamente realizzati in Italia e conformi alle normative europee. La nostra linea di sacchi da boxe \u00e8 prodotta con <strong>sistema brevettato<\/strong>: uno speciale riempimento che\u00a0<strong>simula la colonna vertebrale<\/strong> dell\u2019avversario per un allenamento pi\u00f9 reale.\r\n\r\nL\u2019imbottitura in agglomerato di poliuretano espanso riciclato e riciclabile infinite volte\u00a0<strong>assorbe efficacemente i colpi <\/strong>e consente al sacco di mantenere inalterata la forma nel corso degli anni.\r\n\r\nPer i nostri sacchi da boxe offriamo una <strong>garanzia di 5 anni<\/strong>. Per scoprire i prezzi dei nostri sacchi da boxe, richiedi un preventivo gratuito.\r\n\r\n<\/div>","link":"https:\/\/itatami.it\/fr\/categoria-prodotti\/sacs-de-boxe\/","name":"Sacchi da Boxe","slug":"sacchi-da-boxe","taxonomy":"prodotti","parent":81,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sacchi da Boxe - iTatami<\/title>\n<meta name=\"description\" content=\"Sacchi da boxe 100% Made in Italy con sistema che simula la colonna vertebrale dell&#039;avversario. Garanzia 5 anni. Richiedi un preventivo gratuito ora.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itatami.it\/fr\/categorie-de-produits\/sacs-de-boxe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sacchi da Boxe - iTatami\" \/>\n<meta property=\"og:description\" content=\"Sacchi da boxe 100% Made in Italy con sistema che simula la colonna vertebrale dell&#039;avversario. Garanzia 5 anni. Richiedi un preventivo gratuito ora.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itatami.it\/fr\/categorie-de-produits\/sacs-de-boxe\/\" \/>\n<meta property=\"og:site_name\" content=\"iTatami\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itatami.it\/wp-content\/uploads\/2023\/12\/Immagine-del-sito-iTatami.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/itatami.it\\\/fr\\\/categorie-de-produits\\\/sacs-de-boxe\\\/\",\"url\":\"https:\\\/\\\/itatami.it\\\/fr\\\/categorie-de-produits\\\/sacs-de-boxe\\\/\",\"name\":\"Sacchi da Boxe - iTatami\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itatami.it\\\/#website\"},\"description\":\"Sacchi da boxe 100% Made in Italy con sistema che simula la colonna vertebrale dell'avversario. Garanzia 5 anni. Richiedi un preventivo gratuito ora.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itatami.it\\\/fr\\\/categorie-de-produits\\\/sacs-de-boxe\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itatami.it\\\/fr\\\/categorie-de-produits\\\/sacs-de-boxe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itatami.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attrezzature Boxe\",\"item\":\"https:\\\/\\\/itatami.it\\\/fr\\\/categorie-de-produits\\\/equipement-de-boxe-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sacchi da Boxe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itatami.it\\\/#website\",\"url\":\"https:\\\/\\\/itatami.it\\\/\",\"name\":\"iTatami\",\"description\":\"Produttrice di tatami, materassi e tappeti per sport e Arti Marziali\",\"publisher\":{\"@id\":\"https:\\\/\\\/itatami.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itatami.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/itatami.it\\\/#organization\",\"name\":\"iTatami s.r.l.\",\"url\":\"https:\\\/\\\/itatami.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/itatami.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/itatami.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Progetto-senza-titolo-3.png\",\"contentUrl\":\"https:\\\/\\\/itatami.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Progetto-senza-titolo-3.png\",\"width\":100,\"height\":100,\"caption\":\"iTatami s.r.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/itatami.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sacchi da Boxe - iTatami","description":"Sacchi da boxe 100% Made in Italy con sistema che simula la colonna vertebrale dell'avversario. Garanzia 5 anni. Richiedi un preventivo gratuito ora.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itatami.it\/fr\/categorie-de-produits\/sacs-de-boxe\/","og_locale":"fr_FR","og_type":"article","og_title":"Sacchi da Boxe - iTatami","og_description":"Sacchi da boxe 100% Made in Italy con sistema che simula la colonna vertebrale dell'avversario. Garanzia 5 anni. Richiedi un preventivo gratuito ora.","og_url":"https:\/\/itatami.it\/fr\/categorie-de-produits\/sacs-de-boxe\/","og_site_name":"iTatami","og_image":[{"width":1200,"height":675,"url":"https:\/\/itatami.it\/wp-content\/uploads\/2023\/12\/Immagine-del-sito-iTatami.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/itatami.it\/fr\/categorie-de-produits\/sacs-de-boxe\/","url":"https:\/\/itatami.it\/fr\/categorie-de-produits\/sacs-de-boxe\/","name":"Sacchi da Boxe - iTatami","isPartOf":{"@id":"https:\/\/itatami.it\/#website"},"description":"Sacchi da boxe 100% Made in Italy con sistema che simula la colonna vertebrale dell'avversario. Garanzia 5 anni. Richiedi un preventivo gratuito ora.","breadcrumb":{"@id":"https:\/\/itatami.it\/fr\/categorie-de-produits\/sacs-de-boxe\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/itatami.it\/fr\/categorie-de-produits\/sacs-de-boxe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itatami.it\/"},{"@type":"ListItem","position":2,"name":"Attrezzature Boxe","item":"https:\/\/itatami.it\/fr\/categorie-de-produits\/equipement-de-boxe-2\/"},{"@type":"ListItem","position":3,"name":"Sacchi da Boxe"}]},{"@type":"WebSite","@id":"https:\/\/itatami.it\/#website","url":"https:\/\/itatami.it\/","name":"iTatami","description":"Produttrice di tatami, materassi e tappeti per sport e Arti Marziali","publisher":{"@id":"https:\/\/itatami.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itatami.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/itatami.it\/#organization","name":"iTatami s.r.l.","url":"https:\/\/itatami.it\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/itatami.it\/#\/schema\/logo\/image\/","url":"https:\/\/itatami.it\/wp-content\/uploads\/2023\/12\/Progetto-senza-titolo-3.png","contentUrl":"https:\/\/itatami.it\/wp-content\/uploads\/2023\/12\/Progetto-senza-titolo-3.png","width":100,"height":100,"caption":"iTatami s.r.l."},"image":{"@id":"https:\/\/itatami.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/itatami.it\/fr\/wp-json\/wp\/v2\/prodotti\/82","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itatami.it\/fr\/wp-json\/wp\/v2\/prodotti"}],"about":[{"href":"https:\/\/itatami.it\/fr\/wp-json\/wp\/v2\/taxonomies\/prodotti"}],"up":[{"embeddable":true,"href":"https:\/\/itatami.it\/fr\/wp-json\/wp\/v2\/prodotti\/81"}],"wp:post_type":[{"href":"https:\/\/itatami.it\/fr\/wp-json\/wp\/v2\/pages?prodotti=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}