{"id":89,"count":4,"description":"<div style=\"text-align: left;padding: 0% 15% 5px 15%\"><h2 style=\"line-height: 100%\">Produciamo tappeti e pavimentazione per ginnastica artistica e ritmica<\/h2>\r\nI prodotti che produciamo sono: <strong>pavimentazione pieghevole<\/strong>, <strong>tappeto per i tes<\/strong>t e <strong>corsie per esercizi<\/strong> <strong>a corpo libero<\/strong>.\r\n\r\nI nostri prodotti sono interamente <strong>prodotti in Italia<\/strong> con materiali di alta qualit\u00e0. I nostri <strong>tappeti per ginnastica<\/strong> artistica e ritmica sono rivestiti con la nostra soluzione Btex, il che li rende ignifughi.\r\n\r\nPer aumentare la sicurezza durante le performance durante i vostri allenamenti o gare sono imbottiti con materiale riciclato e riciclabile di alta qualit\u00e0 di nostra produzione.\r\n\r\nGrazie a tutte queste particolarit\u00e0 tutti i nostri prodotti hanno una <strong>garanzia di 5 anni<\/strong>.<\/h2>","link":"https:\/\/itatami.it\/en\/categoria-prodotti\/gymnastics-mats\/","name":"Tappeti Ginnastica","slug":"tappeti-ginnastica","taxonomy":"prodotti","parent":86,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tappeti Ginnastica - iTatami<\/title>\n<meta name=\"description\" content=\"Tappeti e pavimentazione per ginnastica artistica e ritmica: sicurezza, qualit\u00e0 e sostenibilit\u00e0. 100% Italiani. 5 anni di garanzia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itatami.it\/en\/categorie-de-produits\/tapis-de-gymnastique\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tappeti Ginnastica - iTatami\" \/>\n<meta property=\"og:description\" content=\"Tappeti e pavimentazione per ginnastica artistica e ritmica: sicurezza, qualit\u00e0 e sostenibilit\u00e0. 100% Italiani. 5 anni di garanzia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itatami.it\/en\/categorie-de-produits\/tapis-de-gymnastique\/\" \/>\n<meta property=\"og:site_name\" content=\"iTatami\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itatami.it\/wp-content\/uploads\/2023\/12\/Immagine-del-sito-iTatami.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/itatami.it\\\/fr\\\/categorie-de-produits\\\/tapis-de-gymnastique\\\/\",\"url\":\"https:\\\/\\\/itatami.it\\\/fr\\\/categorie-de-produits\\\/tapis-de-gymnastique\\\/\",\"name\":\"Tappeti Ginnastica - iTatami\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itatami.it\\\/#website\"},\"description\":\"Tappeti e pavimentazione per ginnastica artistica e ritmica: sicurezza, qualit\u00e0 e sostenibilit\u00e0. 100% Italiani. 5 anni di garanzia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itatami.it\\\/fr\\\/categorie-de-produits\\\/tapis-de-gymnastique\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itatami.it\\\/fr\\\/categorie-de-produits\\\/tapis-de-gymnastique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itatami.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attrezzatura Ginnastica\",\"item\":\"https:\\\/\\\/itatami.it\\\/categoria-prodotti\\\/attrezzatura-ginnastica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tappeti Ginnastica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itatami.it\\\/#website\",\"url\":\"https:\\\/\\\/itatami.it\\\/\",\"name\":\"iTatami\",\"description\":\"Produttrice di tatami, materassi e tappeti per sport e Arti Marziali\",\"publisher\":{\"@id\":\"https:\\\/\\\/itatami.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itatami.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/itatami.it\\\/#organization\",\"name\":\"iTatami s.r.l.\",\"url\":\"https:\\\/\\\/itatami.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/itatami.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/itatami.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Progetto-senza-titolo-3.png\",\"contentUrl\":\"https:\\\/\\\/itatami.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Progetto-senza-titolo-3.png\",\"width\":100,\"height\":100,\"caption\":\"iTatami s.r.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/itatami.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tappeti Ginnastica - iTatami","description":"Tappeti e pavimentazione per ginnastica artistica e ritmica: sicurezza, qualit\u00e0 e sostenibilit\u00e0. 100% Italiani. 5 anni di garanzia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itatami.it\/en\/categorie-de-produits\/tapis-de-gymnastique\/","og_locale":"en_GB","og_type":"article","og_title":"Tappeti Ginnastica - iTatami","og_description":"Tappeti e pavimentazione per ginnastica artistica e ritmica: sicurezza, qualit\u00e0 e sostenibilit\u00e0. 100% Italiani. 5 anni di garanzia.","og_url":"https:\/\/itatami.it\/en\/categorie-de-produits\/tapis-de-gymnastique\/","og_site_name":"iTatami","og_image":[{"width":1200,"height":675,"url":"https:\/\/itatami.it\/wp-content\/uploads\/2023\/12\/Immagine-del-sito-iTatami.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/itatami.it\/fr\/categorie-de-produits\/tapis-de-gymnastique\/","url":"https:\/\/itatami.it\/fr\/categorie-de-produits\/tapis-de-gymnastique\/","name":"Tappeti Ginnastica - iTatami","isPartOf":{"@id":"https:\/\/itatami.it\/#website"},"description":"Tappeti e pavimentazione per ginnastica artistica e ritmica: sicurezza, qualit\u00e0 e sostenibilit\u00e0. 100% Italiani. 5 anni di garanzia.","breadcrumb":{"@id":"https:\/\/itatami.it\/fr\/categorie-de-produits\/tapis-de-gymnastique\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/itatami.it\/fr\/categorie-de-produits\/tapis-de-gymnastique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itatami.it\/"},{"@type":"ListItem","position":2,"name":"Attrezzatura Ginnastica","item":"https:\/\/itatami.it\/categoria-prodotti\/attrezzatura-ginnastica\/"},{"@type":"ListItem","position":3,"name":"Tappeti Ginnastica"}]},{"@type":"WebSite","@id":"https:\/\/itatami.it\/#website","url":"https:\/\/itatami.it\/","name":"iTatami","description":"Produttrice di tatami, materassi e tappeti per sport e Arti Marziali","publisher":{"@id":"https:\/\/itatami.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itatami.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/itatami.it\/#organization","name":"iTatami s.r.l.","url":"https:\/\/itatami.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/itatami.it\/#\/schema\/logo\/image\/","url":"https:\/\/itatami.it\/wp-content\/uploads\/2023\/12\/Progetto-senza-titolo-3.png","contentUrl":"https:\/\/itatami.it\/wp-content\/uploads\/2023\/12\/Progetto-senza-titolo-3.png","width":100,"height":100,"caption":"iTatami s.r.l."},"image":{"@id":"https:\/\/itatami.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/itatami.it\/en\/wp-json\/wp\/v2\/prodotti\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itatami.it\/en\/wp-json\/wp\/v2\/prodotti"}],"about":[{"href":"https:\/\/itatami.it\/en\/wp-json\/wp\/v2\/taxonomies\/prodotti"}],"up":[{"embeddable":true,"href":"https:\/\/itatami.it\/en\/wp-json\/wp\/v2\/prodotti\/86"}],"wp:post_type":[{"href":"https:\/\/itatami.it\/en\/wp-json\/wp\/v2\/pages?prodotti=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}